{"id":5230,"date":"2024-08-02T15:39:49","date_gmt":"2024-08-02T18:39:49","guid":{"rendered":"https:\/\/canosa.com\/?p=5230"},"modified":"2024-08-02T15:39:50","modified_gmt":"2024-08-02T18:39:50","slug":"nuevas-modificaciones-en-materia-administrativa","status":"publish","type":"post","link":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/","title":{"rendered":"Nuevas modificaciones en materia Administrativa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El 8 de julio de 2024, se public\u00f3 en el Bolet\u00edn Oficial el Decreto Reglamentario 592\/2024 (el \u201c<span style=\"text-decoration: underline;\">Decreto<\/span>\u201d) que reglamenta la Ley 27.742 Bases y Puntos de Partida para la Libertad de los Argentinos (la \u201c<span style=\"text-decoration: underline;\">Ley<\/span>\u201d o \u201c<span style=\"text-decoration: underline;\">Ley Bases<\/span>\u201d), que en el T\u00edtulo I y II, introduce modificaciones de materia administrativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n detallamos un resumen de las modificaciones m\u00e1s importantes que introducen los T\u00edtulos I y II de la Ley Bases:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"text-decoration: underline;\">Declaraci\u00f3n de Emergencia y Delegaci\u00f3n de Facultades<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva Ley Bases declara la emergencia en diversas \u00e1reas, delega funciones legislativas al Poder Ejecutivo, promueve la reorganizaci\u00f3n del Sector P\u00fablico Nacional y autoriza privatizaciones, entre otras medidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">1. Declaraci\u00f3n de Emergencia<\/span>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Se declara la emergencia p\u00fablica en los \u00e1mbitos administrativo, econ\u00f3mico, financiero y energ\u00e9tico por un a\u00f1o.<\/li><li>Esta declaraci\u00f3n respalda la delegaci\u00f3n de facultades al Poder Ejecutivo, conforme al art\u00edculo 76 de la Constituci\u00f3n Nacional.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">2. Delegaci\u00f3n de Facultades:<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se otorgan al Poder Ejecutivo facultades para:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Mejorar la eficiencia del Estado, logrando una gesti\u00f3n p\u00fablica transparente, r\u00e1pida, eficiente y de calidad.<\/li><li>Reducir el sobredimensionamiento de la&nbsp; estructura estatal para disminuir el d\u00e9ficit, hacer m\u00e1s transparente el gasto y equilibrar las cuentas p\u00fablicas.<\/li><li>Asegurar un control interno efectivo en la Administraci\u00f3n P\u00fablica Nacional para garantizar la transparencia en la administraci\u00f3n de las finanzas p\u00fablicas.<\/li><li>El Poder Ejecutivo deber\u00e1 informar mensualmente al Congreso sobre el uso de estas facultades y los resultados obtenidos.<\/li><li>Todos los decretos emitidos bajo estas facultades estar\u00e1n sujetos a revisi\u00f3n legislativa posterior, conforme al art\u00edculo 100 inciso 12 de la Constituci\u00f3n Nacional y la ley 26122.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"text-decoration: underline;\">Reorganizaci\u00f3n del Sector P\u00fablico Nacional<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ley de Bases impulsa la reorganizaci\u00f3n del Sector P\u00fablico Nacional en el contexto de la emergencia declarada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">1. Facultades al Poder Ejecutivo<\/span>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Modificar o eliminar competencias, funciones o responsabilidades de la administraci\u00f3n central y de organismos descentralizados creados por ley.<\/li><li>Reorganizar, modificar o transformar la estructura jur\u00eddica de estos organismos, centralizarlos, fusionarlos, disolverlos o transferirlos a las provincias o a la Ciudad de Buenos Aires.<\/li><li>Modificar, transformar, fusionar, escindir, reorganizar, reconformar o transferir a las provincias o a la Ciudad de Buenos Aires las empresas y sociedades bajo control estatal.<\/li><li>Autorizar la intervenci\u00f3n de organismos descentralizados y de empresas y sociedades estatales por un a\u00f1o.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">2. Restricciones<\/span>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Estas facultades no se aplicar\u00e1n a universidades nacionales, \u00f3rganos del Poder Judicial, Legislativo, Ministerio P\u00fablico y otros organismos espec\u00edficos como la ANMAT, CNV, UIF y ENACOM.<\/li><li>Modificar, transformar, unificar, disolver o liquidar fondos fiduciarios p\u00fablicos.<\/li><li>Declarar \u201csujeta a privatizaci\u00f3n\u201d a ocho empresas y sociedades de propiedad estatal, seg\u00fan los t\u00e9rminos de la Ley 23696 de Reforma del Estado. Entre ellas, el Complejo Carbon\u00edfero, Ferroviario, Portuario y Energ\u00e9tico a cargo de Yacimientos Carbon\u00edferos R\u00edo Turbio (YCRT) se declara sujeto a privatizaci\u00f3n. La privatizaci\u00f3n incluir\u00e1 la posibilidad de:<\/li><\/ul>\n\n\n\n<ol class=\"wp-block-list\"><li>&nbsp;Organizar un programa de propiedad participada.<\/li><li>Incorporar capital privado manteniendo el control estatal o la participaci\u00f3n mayoritaria en el capital social.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la liquidaci\u00f3n de empresas estatales, se deber\u00e1n cumplir las siguientes disposiciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Solo se podr\u00e1n vender los bienes necesarios para cancelar los pasivos.<\/li><li>En caso de insuficiencia de bienes, se requerir\u00e1 a la Agencia de Administraci\u00f3n de Bienes del Estado la enajenaci\u00f3n de los bienes restantes<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de privatizaci\u00f3n debe desarrollarse con transparencia, competencia, m\u00e1xima concurrencia, gobierno abierto, eficiencia y eficacia en el uso de recursos. La reglamentaci\u00f3n establecer\u00e1 plazos y modalidades espec\u00edficas para garantizar la debida publicidad y difusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"text-decoration: underline;\">Modificaciones a Leyes y Contratos<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">1. Ley de Procedimientos Administrativos:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La Ley de Bases introduce amplias modificaciones a la Ley de Procedimientos Administrativos, incorporando principios y doctrinas modernas para reforzar las garant\u00edas de los ciudadanos frente a la Administraci\u00f3n P\u00fablica.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">2. Renegociaci\u00f3n de Contratos: <\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Se autoriza al Poder Ejecutivo a renegociar o rescindir contratos de obra p\u00fablica, concesi\u00f3n, construcci\u00f3n o provisi\u00f3n de bienes y servicios superiores a ciertos montos y celebrados antes del 10 de diciembre de 2023.<\/li><li>Se considera inapropiado suspender o rescindir contratos de obra p\u00fablica ejecutados en un 80% o con financiamiento internacional, permitiendo su reanudaci\u00f3n mediante acuerdo entre comitente y contratista.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">3. Exclusiones y Controversias:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Se excluyen de la renegociaci\u00f3n o terminaci\u00f3n los contratos firmados durante la privatizaci\u00f3n de los a\u00f1os 1990 y los firmados bajo reg\u00edmenes de promoci\u00f3n.<\/li><li>Se faculta al Poder Ejecutivo para realizar acuerdos transaccionales en caso de controversias o incumplimientos contractuales, con la intervenci\u00f3n de la Procuraci\u00f3n del Tesoro de la Naci\u00f3n y la Sindicatura General de la Naci\u00f3n.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"text-decoration: underline;\">4. Ley de Concesi\u00f3n de Obra P\u00fablica<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Se introducen modificaciones para brindar mayor flexibilidad, seguridad jur\u00eddica y estabilidad a los contratos bajo este r\u00e9gimen.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Ley entr\u00f3 en vigencia con su publicaci\u00f3n en el Bolet\u00edn Oficial el d\u00eda 8 de julio de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 8 de julio de 2024, se public\u00f3 en el Bolet\u00edn Oficial el Decreto Reglamentario 592\/2024 (el \u201cDecreto\u201d) que reglamenta la Ley 27.742 Bases y Puntos de Partida para la Libertad de los Argentinos (la \u201cLey\u201d o \u201cLey Bases\u201d), que en el T\u00edtulo I y II, introduce modificaciones de materia administrativa. A continuaci\u00f3n detallamos un &hellip; <a href=\"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/\">Continued<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5230","post","type-post","status-publish","format-standard","hentry","category-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevas modificaciones en materia Administrativa - Canosa Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevas modificaciones en materia Administrativa - Canosa Abogados\" \/>\n<meta property=\"og:description\" content=\"El 8 de julio de 2024, se public\u00f3 en el Bolet\u00edn Oficial el Decreto Reglamentario 592\/2024 (el \u201cDecreto\u201d) que reglamenta la Ley 27.742 Bases y Puntos de Partida para la Libertad de los Argentinos (la \u201cLey\u201d o \u201cLey Bases\u201d), que en el T\u00edtulo I y II, introduce modificaciones de materia administrativa. A continuaci\u00f3n detallamos un &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Canosa Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T18:39:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T18:39:50+00:00\" \/>\n<meta name=\"author\" content=\"canosa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"canosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/nuevas-modificaciones-en-materia-administrativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/nuevas-modificaciones-en-materia-administrativa\\\/\"},\"author\":{\"name\":\"canosa\",\"@id\":\"https:\\\/\\\/canosa.com\\\/#\\\/schema\\\/person\\\/76176820718fc975b0b091e8a397a6ff\"},\"headline\":\"Nuevas modificaciones en materia Administrativa\",\"datePublished\":\"2024-08-02T18:39:49+00:00\",\"dateModified\":\"2024-08-02T18:39:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/nuevas-modificaciones-en-materia-administrativa\\\/\"},\"wordCount\":846,\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/nuevas-modificaciones-en-materia-administrativa\\\/\",\"url\":\"https:\\\/\\\/canosa.com\\\/es\\\/nuevas-modificaciones-en-materia-administrativa\\\/\",\"name\":\"Nuevas modificaciones en materia Administrativa - Canosa Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/#website\"},\"datePublished\":\"2024-08-02T18:39:49+00:00\",\"dateModified\":\"2024-08-02T18:39:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/#\\\/schema\\\/person\\\/76176820718fc975b0b091e8a397a6ff\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canosa.com\\\/es\\\/nuevas-modificaciones-en-materia-administrativa\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canosa.com\\\/#website\",\"url\":\"https:\\\/\\\/canosa.com\\\/\",\"name\":\"Canosa Abogados\",\"description\":\"Abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canosa.com\\\/#\\\/schema\\\/person\\\/76176820718fc975b0b091e8a397a6ff\",\"name\":\"canosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g\",\"caption\":\"canosa\"},\"url\":\"https:\\\/\\\/canosa.com\\\/es\\\/author\\\/canosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevas modificaciones en materia Administrativa - Canosa Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevas modificaciones en materia Administrativa - Canosa Abogados","og_description":"El 8 de julio de 2024, se public\u00f3 en el Bolet\u00edn Oficial el Decreto Reglamentario 592\/2024 (el \u201cDecreto\u201d) que reglamenta la Ley 27.742 Bases y Puntos de Partida para la Libertad de los Argentinos (la \u201cLey\u201d o \u201cLey Bases\u201d), que en el T\u00edtulo I y II, introduce modificaciones de materia administrativa. A continuaci\u00f3n detallamos un &hellip; Continued","og_url":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/","og_site_name":"Canosa Abogados","article_published_time":"2024-08-02T18:39:49+00:00","article_modified_time":"2024-08-02T18:39:50+00:00","author":"canosa","twitter_misc":{"Written by":"canosa","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/#article","isPartOf":{"@id":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/"},"author":{"name":"canosa","@id":"https:\/\/canosa.com\/#\/schema\/person\/76176820718fc975b0b091e8a397a6ff"},"headline":"Nuevas modificaciones en materia Administrativa","datePublished":"2024-08-02T18:39:49+00:00","dateModified":"2024-08-02T18:39:50+00:00","mainEntityOfPage":{"@id":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/"},"wordCount":846,"articleSection":["Art\u00edculos"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/","url":"https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/","name":"Nuevas modificaciones en materia Administrativa - Canosa Abogados","isPartOf":{"@id":"https:\/\/canosa.com\/#website"},"datePublished":"2024-08-02T18:39:49+00:00","dateModified":"2024-08-02T18:39:50+00:00","author":{"@id":"https:\/\/canosa.com\/#\/schema\/person\/76176820718fc975b0b091e8a397a6ff"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canosa.com\/es\/nuevas-modificaciones-en-materia-administrativa\/"]}]},{"@type":"WebSite","@id":"https:\/\/canosa.com\/#website","url":"https:\/\/canosa.com\/","name":"Canosa Abogados","description":"Abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/canosa.com\/#\/schema\/person\/76176820718fc975b0b091e8a397a6ff","name":"canosa","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g","caption":"canosa"},"url":"https:\/\/canosa.com\/es\/author\/canosa\/"}]}},"_links":{"self":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts\/5230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/comments?post=5230"}],"version-history":[{"count":1,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts\/5230\/revisions"}],"predecessor-version":[{"id":5231,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts\/5230\/revisions\/5231"}],"wp:attachment":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/media?parent=5230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/categories?post=5230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/tags?post=5230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}