{"id":6117,"date":"2025-12-23T10:28:58","date_gmt":"2025-12-23T13:28:58","guid":{"rendered":"https:\/\/canosa.com\/?p=6117"},"modified":"2025-12-23T10:29:07","modified_gmt":"2025-12-23T13:29:07","slug":"fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas","status":"publish","type":"post","link":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/","title":{"rendered":"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El dia 11 de septiembre de 2025 Sala V de la C\u00e1mara Nacional de Apelaciones en lo Contencioso Administrativo Federal (la \u201c<span style=\"text-decoration: underline;\">C\u00e1mara<\/span>\u201d) dict\u00f3 sentencia en la causa \u201c<em>Norauto Argentina SA (Tf 35897-I) c\/ Direcci\u00f3n General Impositiva s\/Recurso Directo de Organismo Externo<\/em>\u201d confirm\u00f3 la sentencia del Tribunal Fiscal de la Naci\u00f3n (el \u201c<span style=\"text-decoration: underline;\">Tribunal<\/span>&#8220;) que resolvi\u00f3 que la absorci\u00f3n de p\u00e9rdidas mediante aportes irrevocables no genera efectos impositivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hechos<\/strong><br>El Fisco determin\u00f3 de oficio un ajuste en el impuesto a las ganancias y aplic\u00f3 multa por omisi\u00f3n a Norauto Argentina SA (\u201c<span style=\"text-decoration: underline;\">Norauto<\/span>\u201d) por no haber declarado como gravada la renta obtenida por la \u201ccondonaci\u00f3n\u201d de los aportes irrevocables para absorci\u00f3n de p\u00e9rdidas de los per\u00edodos fiscales 2006-2007 efectuados por la empresa controlante argumentando que los aportes irrevocables deb\u00edan ser tratados como un \u201cenriquecimiento a t\u00edtulo gratuito\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Norauto interpuso un recurso de apelaci\u00f3n ante el Tribunal contra la resoluci\u00f3n al argumentar que la operaci\u00f3n se trat\u00f3 de un movimiento de capital y no de una transacci\u00f3n que generar\u00e1 resultados, ni p\u00e9rdidas ni ganancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acorde al informe pericial la asamblea extraordinaria hab\u00eda resuelto aumentar su capital social mediante la capitalizaci\u00f3n de las cuentas ajustar integral de capital social y aportes irrevocables previa deducci\u00f3n de los resultados negativos no asignados, como resultado la sumatoria de ambas cuentas m\u00e1s el capital existente dieron un resultado equivalente al capital existente en el per\u00edodo fiscal anterior (2005).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Tribunal con el precedente \u201c<em>Flint Ink Argentina SRL<\/em>\u201d, que estableci\u00f3 que los aportes irrevocables destinados a absorber p\u00e9rdidas no constituyen ganancia gravada, resolvi\u00f3 revocar la resoluci\u00f3n de oficio del Fisco debido a que no result\u00f3 acreditado el enriquecimiento a t\u00edtulo gratuito, al no advertirse una condonaci\u00f3n de aportes ni el incremento del patrimonio neto por la absorci\u00f3n de p\u00e9rdidas con aportes irrevocables de los accionistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Fisco apel\u00f3 la sentencia del Tribunal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fallo de la C\u00e1mara<\/strong><br>La C\u00e1mara volvi\u00f3 a citar el precedente \u201c<em>Flint Ink Argentina SRL<\/em>\u201d y concluy\u00f3 que la afectaci\u00f3n de aportes irrevocables a la conformaci\u00f3n de una reserva voluntaria para absorber p\u00e9rdidas no implica una modificaci\u00f3n cuantitativa del Patrimonio Neto, al no formar estos aportes parte del pasivo de la Sociedad en ning\u00fan momento, por lo cual se tratar\u00eda de una \u201cmera reclasificaci\u00f3n entre sus componentes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto de la condonaci\u00f3n la C\u00e1mara destac\u00f3 que surge del acta de asamblea y de la prueba pericial contable que el aporte dinerario ten\u00eda como destino la actividad empresarial y revest\u00eda car\u00e1cter definitivo, siendo manifiesta la intenci\u00f3n del socio controlante de realizar la integraci\u00f3n irrevocable hasta su concreta capitalizaci\u00f3n a los fines de la absorci\u00f3n de quebrantos, por lo que dif\u00edcilmente podr\u00eda considerarse, a efectos tributarios, como un pr\u00e9stamo que pueda ser posteriormente perdonado y genere as\u00ed un aumento patrimonial sujeto al Impuesto a las Ganancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo cual la C\u00e1mara resolvi\u00f3 rechazar el recurso de apelaci\u00f3n interpuesto por el Fisco y confirm\u00f3 la sentencia de primera instancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dia 11 de septiembre de 2025 Sala V de la C\u00e1mara Nacional de Apelaciones en lo Contencioso Administrativo Federal (la \u201cC\u00e1mara\u201d) dict\u00f3 sentencia en la causa \u201cNorauto Argentina SA (Tf 35897-I) c\/ Direcci\u00f3n General Impositiva s\/Recurso Directo de Organismo Externo\u201d confirm\u00f3 la sentencia del Tribunal Fiscal de la Naci\u00f3n (el \u201cTribunal&#8220;) que resolvi\u00f3 que &hellip; <a href=\"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/\">Continued<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6117","post","type-post","status-publish","format-standard","hentry","category-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas - Canosa Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas - Canosa Abogados\" \/>\n<meta property=\"og:description\" content=\"El dia 11 de septiembre de 2025 Sala V de la C\u00e1mara Nacional de Apelaciones en lo Contencioso Administrativo Federal (la \u201cC\u00e1mara\u201d) dict\u00f3 sentencia en la causa \u201cNorauto Argentina SA (Tf 35897-I) c\/ Direcci\u00f3n General Impositiva s\/Recurso Directo de Organismo Externo\u201d confirm\u00f3 la sentencia del Tribunal Fiscal de la Naci\u00f3n (el \u201cTribunal&#8220;) que resolvi\u00f3 que &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canosa Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-23T13:28:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-23T13:29:07+00:00\" \/>\n<meta name=\"author\" content=\"canosa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"canosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\\\/\"},\"author\":{\"name\":\"canosa\",\"@id\":\"https:\\\/\\\/canosa.com\\\/#\\\/schema\\\/person\\\/76176820718fc975b0b091e8a397a6ff\"},\"headline\":\"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas\",\"datePublished\":\"2025-12-23T13:28:58+00:00\",\"dateModified\":\"2025-12-23T13:29:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\\\/\"},\"wordCount\":544,\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canosa.com\\\/es\\\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\\\/\",\"url\":\"https:\\\/\\\/canosa.com\\\/es\\\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\\\/\",\"name\":\"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas - Canosa Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/#website\"},\"datePublished\":\"2025-12-23T13:28:58+00:00\",\"dateModified\":\"2025-12-23T13:29:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canosa.com\\\/#\\\/schema\\\/person\\\/76176820718fc975b0b091e8a397a6ff\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canosa.com\\\/es\\\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canosa.com\\\/#website\",\"url\":\"https:\\\/\\\/canosa.com\\\/\",\"name\":\"Canosa Abogados\",\"description\":\"Abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canosa.com\\\/#\\\/schema\\\/person\\\/76176820718fc975b0b091e8a397a6ff\",\"name\":\"canosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g\",\"caption\":\"canosa\"},\"url\":\"https:\\\/\\\/canosa.com\\\/es\\\/author\\\/canosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas - Canosa Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/","og_locale":"es_ES","og_type":"article","og_title":"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas - Canosa Abogados","og_description":"El dia 11 de septiembre de 2025 Sala V de la C\u00e1mara Nacional de Apelaciones en lo Contencioso Administrativo Federal (la \u201cC\u00e1mara\u201d) dict\u00f3 sentencia en la causa \u201cNorauto Argentina SA (Tf 35897-I) c\/ Direcci\u00f3n General Impositiva s\/Recurso Directo de Organismo Externo\u201d confirm\u00f3 la sentencia del Tribunal Fiscal de la Naci\u00f3n (el \u201cTribunal&#8220;) que resolvi\u00f3 que &hellip; Continued","og_url":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/","og_site_name":"Canosa Abogados","article_published_time":"2025-12-23T13:28:58+00:00","article_modified_time":"2025-12-23T13:29:07+00:00","author":"canosa","twitter_misc":{"Written by":"canosa","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/#article","isPartOf":{"@id":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/"},"author":{"name":"canosa","@id":"https:\/\/canosa.com\/#\/schema\/person\/76176820718fc975b0b091e8a397a6ff"},"headline":"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas","datePublished":"2025-12-23T13:28:58+00:00","dateModified":"2025-12-23T13:29:07+00:00","mainEntityOfPage":{"@id":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/"},"wordCount":544,"articleSection":["Art\u00edculos"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/","url":"https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/","name":"Fallo respecto del tratamiento fiscal de los aportes irrevocables destinados a la absorci\u00f3n de p\u00e9rdidas - Canosa Abogados","isPartOf":{"@id":"https:\/\/canosa.com\/#website"},"datePublished":"2025-12-23T13:28:58+00:00","dateModified":"2025-12-23T13:29:07+00:00","author":{"@id":"https:\/\/canosa.com\/#\/schema\/person\/76176820718fc975b0b091e8a397a6ff"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canosa.com\/es\/fallo-respecto-del-tratamiento-fiscal-de-los-aportes-irrevocables-destinados-a-la-absorcion-de-perdidas\/"]}]},{"@type":"WebSite","@id":"https:\/\/canosa.com\/#website","url":"https:\/\/canosa.com\/","name":"Canosa Abogados","description":"Abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/canosa.com\/#\/schema\/person\/76176820718fc975b0b091e8a397a6ff","name":"canosa","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cd643e6a187fe6fe0aeed422915178fc5afba5be0d92e9868b082f185408f85?s=96&d=mm&r=g","caption":"canosa"},"url":"https:\/\/canosa.com\/es\/author\/canosa\/"}]}},"_links":{"self":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts\/6117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/comments?post=6117"}],"version-history":[{"count":1,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts\/6117\/revisions"}],"predecessor-version":[{"id":6118,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/posts\/6117\/revisions\/6118"}],"wp:attachment":[{"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/media?parent=6117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/categories?post=6117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canosa.com\/es\/wp-json\/wp\/v2\/tags?post=6117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}